{"id":2404,"date":"2021-10-09T16:48:28","date_gmt":"2021-10-09T20:48:28","guid":{"rendered":"https:\/\/fmahaiti.org\/site\/?p=2404"},"modified":"2021-10-09T16:48:28","modified_gmt":"2021-10-09T20:48:28","slug":"cgxxiv-election-de-la-conseillere-visitatrice-4","status":"publish","type":"post","link":"https:\/\/fmahaiti.org\/site\/2021\/10\/09\/cgxxiv-election-de-la-conseillere-visitatrice-4\/","title":{"rendered":"CGXXIV: Election de la Conseill\u00e8re Visitatrice"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2405 size-full\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Celine-Jacob-768x512-1.jpg?resize=768%2C512&#038;ssl=1\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Celine-Jacob-768x512-1.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Celine-Jacob-768x512-1.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p><strong>Rome (Italie).<\/strong>\u00a0Le 9 octobre 2021,<strong>\u00a0S\u0153ur Celine Jacob<\/strong>, de nationalit\u00e9 indienne,\u00a0a \u00e9t\u00e9 \u00e9lue Conseill\u00e8re Visitatrice de l\u2019Institut des Filles de Marie Auxiliatrice.<\/p>\n<p>Les Conseill\u00e8res d\u00e9l\u00e9gu\u00e9es par la Sup\u00e9rieure G\u00e9n\u00e9rale \u00e0 visiter l\u2019Institut FMA ont pour mission de promouvoir une relation constructive et continue entre les Provinces et la Sup\u00e9rieure G\u00e9n\u00e9rale et son Conseil ainsi qu\u2019une bonne collaboration entre les diff\u00e9rentes communaut\u00e9s provinciales.<\/p>\n<p>Par leur service, elles permettent au Conseil G\u00e9n\u00e9ral d\u2019avoir une meilleure connaissance de la r\u00e9alit\u00e9 de l\u2019Institut, en renfor\u00e7ant l\u2019action apostolique, en valorisant les diff\u00e9rentes cultures, en pleine fid\u00e9lit\u00e9 \u00e0 l\u2019Eglise et \u00e0 Dom Bosco. (C. 132)<\/p>\n<p style=\"text-align: center;\">Nous lui souhaitons nos fraternelles F\u00e9licitations et une f\u00e9conde mission au service de l&rsquo;Institut!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rome (Italie).\u00a0Le 9 octobre 2021,\u00a0S\u0153ur Celine Jacob, de nationalit\u00e9 indienne,\u00a0a \u00e9t\u00e9 \u00e9lue Conseill\u00e8re Visitatrice de l\u2019Institut des Filles de Marie Auxiliatrice. Les Conseill\u00e8res d\u00e9l\u00e9gu\u00e9es par&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[27],"tags":[],"class_list":["post-2404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-de-linstitut"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Celine-Jacob-768x512-1.jpg?fit=768%2C512&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcR5kd-CM","jetpack-related-posts":[{"id":2395,"url":"https:\/\/fmahaiti.org\/site\/2021\/10\/09\/cgxxivelection-de-la-conseillere-visitatrice\/","url_meta":{"origin":2404,"position":0},"title":"CGXXIV:Election de la Conseill\u00e8re Visitatrice","author":"Sr Martha Seide","date":"9 octobre 2021","format":false,"excerpt":"Rome (Italie).\u00a0Le 9 octobre 2021,\u00a0S\u0153ur Maria Assunta Sumiko Inoue\u00a0a \u00e9t\u00e9 r\u00e9\u00e9lue Conseill\u00e8re Visitatrice de l\u2019Institut des Filles de Marie Auxiliatrice. Les Conseill\u00e8res d\u00e9l\u00e9gu\u00e9es par la Sup\u00e9rieure G\u00e9n\u00e9rale \u00e0 visiter l\u2019Institut FMA ont pour mission de promouvoir une relation constructive et continue entre les Provinces et la Sup\u00e9rieure G\u00e9n\u00e9rale et son\u2026","rel":"","context":"Dans &quot;Vie de l'Institut&quot;","block_context":{"text":"Vie de l'Institut","link":"https:\/\/fmahaiti.org\/site\/category\/vie-de-linstitut\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Assunta-Inoue-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Assunta-Inoue-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Assunta-Inoue-768x512-1.jpg?fit=768%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Assunta-Inoue-768x512-1.jpg?fit=768%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2401,"url":"https:\/\/fmahaiti.org\/site\/2021\/10\/09\/cgxxiv-election-de-la-conseillere-visitatrice-3\/","url_meta":{"origin":2404,"position":1},"title":"CGXXIV: Election de la Conseill\u00e8re Visitatrice","author":"Sr Martha Seide","date":"9 octobre 2021","format":false,"excerpt":"Rome (Italie).\u00a0Le 9 octobre 2021,\u00a0S\u0153ur Phyllis Neves, Am\u00e9ricaine (USA), a \u00e9t\u00e9 r\u00e9\u00e9lue Conseill\u00e8re Visitatrice de l\u2019Institut des Filles de Marie Auxiliatrice. Les Conseill\u00e8res d\u00e9l\u00e9gu\u00e9es par la Sup\u00e9rieure G\u00e9n\u00e9rale \u00e0 visiter l\u2019Institut FMA ont pour mission de promouvoir une relation constructive et continue entre les Provinces et la Sup\u00e9rieure G\u00e9n\u00e9rale et\u2026","rel":"","context":"Dans &quot;Vie de l'Institut&quot;","block_context":{"text":"Vie de l'Institut","link":"https:\/\/fmahaiti.org\/site\/category\/vie-de-linstitut\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Phyllis-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Phyllis-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Phyllis-768x512-1.jpg?fit=768%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Phyllis-768x512-1.jpg?fit=768%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2407,"url":"https:\/\/fmahaiti.org\/site\/2021\/10\/09\/cgxxiv-election-de-la-conseillere-visitatrice-5\/","url_meta":{"origin":2404,"position":2},"title":"CGXXIV: Election de la Conseill\u00e8re Visitatrice","author":"Sr Martha Seide","date":"9 octobre 2021","format":false,"excerpt":"Rome (Italie).\u00a0Le 9 octobre 2021,\u00a0S\u0153ur Lidia Strzelczyk, de nationalit\u00e9 Polonaise,\u00a0a \u00e9t\u00e9 \u00e9lue Conseill\u00e8re Visitatrice de l\u2019Institut des Filles de Marie Auxiliatrice. Les Conseill\u00e8res d\u00e9l\u00e9gu\u00e9es par la Sup\u00e9rieure G\u00e9n\u00e9rale \u00e0 visiter l\u2019Institut FMA ont pour mission de promouvoir une relation constructive et continue entre les Provinces et la Sup\u00e9rieure G\u00e9n\u00e9rale et\u2026","rel":"","context":"Dans &quot;Vie de l'Institut&quot;","block_context":{"text":"Vie de l'Institut","link":"https:\/\/fmahaiti.org\/site\/category\/vie-de-linstitut\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Lidia-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Lidia-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Lidia-768x512-1.jpg?fit=768%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Lidia-768x512-1.jpg?fit=768%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2410,"url":"https:\/\/fmahaiti.org\/site\/2021\/10\/09\/cgxxiv-election-de-la-conseillere-visitatrice-6\/","url_meta":{"origin":2404,"position":3},"title":"CGXXIV: Election de la Conseill\u00e8re Visitatrice","author":"Sr Martha Seide","date":"9 octobre 2021","format":false,"excerpt":"Rome (Italie).\u00a0Le 9 octobre 2021,\u00a0S\u0153ur Marta Liliana Riccioli de nationalit\u00e9 Argentine, a \u00e9t\u00e9 \u00e9lue Conseill\u00e8re Visitatrice de l\u2019Institut des Filles de Marie Auxiliatrice. Les Conseill\u00e8res d\u00e9l\u00e9gu\u00e9es par la Sup\u00e9rieure G\u00e9n\u00e9rale \u00e0 visiter l\u2019Institut FMA ont pour mission de promouvoir une relation constructive et continue entre les Provinces et la Sup\u00e9rieure\u2026","rel":"","context":"Dans &quot;Vie de l'Institut&quot;","block_context":{"text":"Vie de l'Institut","link":"https:\/\/fmahaiti.org\/site\/category\/vie-de-linstitut\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Marta-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Marta-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Marta-768x512-1.jpg?fit=768%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Marta-768x512-1.jpg?fit=768%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2391,"url":"https:\/\/fmahaiti.org\/site\/2021\/10\/09\/cgxxiv-election-de-la-conseillere-visitatrice\/","url_meta":{"origin":2404,"position":4},"title":"CGXXIV: Election de la Conseill\u00e8re Visitatrice","author":"Sr Martha Seide","date":"9 octobre 2021","format":false,"excerpt":"Rome (Italie).\u00a0Le 9 octobre 2021,\u00a0S\u0153ur Chantal Mukase Ruzagiriza\u00a0a \u00e9t\u00e9 r\u00e9\u00e9lue Conseill\u00e8re Visitatrice de l\u2019Institut des Filles de Marie Auxiliatrice. Les Conseill\u00e8res d\u00e9l\u00e9gu\u00e9es par la Sup\u00e9rieure G\u00e9n\u00e9rale \u00e0 visiter l\u2019Institut FMA ont pour mission de promouvoir une relation constructive et continue entre les Provinces et la Sup\u00e9rieure G\u00e9n\u00e9rale et son Conseil\u2026","rel":"","context":"Dans &quot;Vie de l'Institut&quot;","block_context":{"text":"Vie de l'Institut","link":"https:\/\/fmahaiti.org\/site\/category\/vie-de-linstitut\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Chantal-Mukase-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Chantal-Mukase-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Chantal-Mukase-768x512-1.jpg?fit=768%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Chantal-Mukase-768x512-1.jpg?fit=768%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2398,"url":"https:\/\/fmahaiti.org\/site\/2021\/10\/09\/cgxxiv-election-de-la-conseillere-visitatrice-2\/","url_meta":{"origin":2404,"position":5},"title":"CGXXIV: Election de la Conseill\u00e8re Visitatrice","author":"Sr Martha Seide","date":"9 octobre 2021","format":false,"excerpt":"Rome (Italie).\u00a0Le 9 octobre 2021,\u00a0s\u0153ur\u00a0Paola Battagliola, italienne, missionnaire \u00e0 Timor Est\/Indon\u00e9sie,\u00a0a \u00e9t\u00e9 R\u00e9\u00e9lue Conseill\u00e8re Visitatrice de l\u2019Institut des Filles de Marie Auxiliatrice. Les Conseill\u00e8res d\u00e9l\u00e9gu\u00e9es par la Sup\u00e9rieure G\u00e9n\u00e9rale \u00e0 visiter l\u2019Institut FMA ont pour mission de promouvoir une relation constructive et continue entre les Provinces et la Sup\u00e9rieure G\u00e9n\u00e9rale\u2026","rel":"","context":"Dans &quot;Vie de l'Institut&quot;","block_context":{"text":"Vie de l'Institut","link":"https:\/\/fmahaiti.org\/site\/category\/vie-de-linstitut\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Paola-Battagliola-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Paola-Battagliola-768x512-1.jpg?fit=768%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Paola-Battagliola-768x512-1.jpg?fit=768%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/10\/Visitatrice-sr-Paola-Battagliola-768x512-1.jpg?fit=768%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts\/2404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/comments?post=2404"}],"version-history":[{"count":1,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts\/2404\/revisions"}],"predecessor-version":[{"id":2406,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts\/2404\/revisions\/2406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/media\/2405"}],"wp:attachment":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/media?parent=2404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/categories?post=2404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/tags?post=2404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}