{"id":15262,"date":"2026-05-10T09:34:44","date_gmt":"2026-05-10T13:34:44","guid":{"rendered":"https:\/\/fmahaiti.org\/site\/?p=15262"},"modified":"2026-05-12T09:37:14","modified_gmt":"2026-05-12T13:37:14","slug":"a-haiti-une-lettre-qui-parle-au-coeur","status":"publish","type":"post","link":"https:\/\/fmahaiti.org\/site\/2026\/05\/10\/a-haiti-une-lettre-qui-parle-au-coeur\/","title":{"rendered":"A Ha\u00efti, une lettre qui parle au c\u0153ur"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-15263 size-full\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-10.48.47-AM.jpeg?resize=750%2C1000&#038;ssl=1\" alt=\"\" width=\"750\" height=\"1000\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-10.48.47-AM.jpeg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-10.48.47-AM.jpeg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><em>Le 30 avril 2026, \u00e0 Port-au-Prince, Ha\u00efti, une \u00e9tudiante de l\u2019Ecole des FMA de P\u00e9tion-Ville a remport\u00e9 le 3\u00e8me prix du concours national de composition de lettre pour les jeunes 2026.<\/em><\/p>\n<p><strong>Port-au-Prince (Ha\u00efti).<\/strong>\u00a0Le 30 avril 2026, la c\u00e9r\u00e9monie de remise des prix du concours national de composition de lettre pour jeunes 2026, organis\u00e9 par le Bureau des Postes d\u2019Ha\u00efti (OPH) sur le th\u00e8me\u00a0:\u00a0<em>\u2018\u2019Ecrit une lettre \u00e0 un ami sur l\u2019importance des relations humaines \u00e0 l\u2019\u00e8re num\u00e9rique\u2019\u2019,<\/em>\u00a0a eu lieu \u00e0 l\u2019H\u00f4tel Karibe \u00e0 Port-au-Prince<\/p>\n<p>Le concours, destin\u00e9 aux jeunes \u00e2g\u00e9s de 9 \u00e0 17 ans, a r\u00e9uni des \u00e9tudiants de diff\u00e9rents Instituts scolaires du pays. Parmi les cinquante Instituts invit\u00e9s \u00e0 participer \u00e0 cette initiative, visant \u00e0 d\u00e9velopper l\u2019esprit critique des jeunes en les invitant \u00e0 r\u00e9fl\u00e9chir \u00e0 des questions actuelles qui touchent profond\u00e9ment leur g\u00e9n\u00e9ration, quatorze \u00e9tudiants ont re\u00e7u un certificat de participation, alors que trois laur\u00e9ats se sont distingu\u00e9s en montant sur le podium.<\/p>\n<p>Dans un monde marqu\u00e9 par l\u2019omnipr\u00e9sence des technologies num\u00e9riques, Les participants ont \u00e9t\u00e9 invit\u00e9 \u00e0 exprimer, par une lettre personnelle, leur compr\u00e9hension des relations humaines et leur importance dans la construction de la personne. Ce th\u00e8me, \u00e0 la fois actuel et universel, a donn\u00e9 naissance \u00e0 des \u0153uvres pleines de sens et d\u2019\u00e9motions.<\/p>\n<p>Parmi les nombreux candidats,\u00a0<strong>Nissa Victoria Eliasme,<\/strong>\u00a0\u00e9tudiante de Secondaire II (S2) \u00e0 l\u2019Ecole\u00a0<em>Sainte Maria Domenica Mazzarello<\/em>\u00a0(CMDM) de P\u00e9tion-Ville des Filles de Marie Auxiliatrice de la Province\u00a0<em>Notre-Dame du Bon Secours<\/em>\u00a0(HAI), s\u2019est particuli\u00e8rement distingu\u00e9e,\u00a0<strong>remportant la troisi\u00e8me place sur le podium.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-15264 size-full\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-10.48.49-AM.jpeg?resize=750%2C1000&#038;ssl=1\" alt=\"\" width=\"750\" height=\"1000\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-10.48.49-AM.jpeg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-10.48.49-AM.jpeg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/strong><\/p>\n<p>Sa lettre a r\u00e9ussi \u00e0 capter l\u2019attention du Jury par la qualit\u00e9 de l\u2019expression, la coh\u00e9rence de pens\u00e9e et la profondeur du regard sur les relations humaines \u00e0 l\u2019\u00e8re num\u00e9rique, d\u00e9montrant une capacit\u00e9 remarquable \u00e0 allier sensibilit\u00e9, lucidit\u00e9 et maturit\u00e9.<\/p>\n<p>Le parcours de Nissa Victoria t\u00e9moigne d\u2019un engagement constant dans sa scolarit\u00e9. Etudiante \u00e0 l\u2019Ecole des FMA depuis sa premi\u00e8re ann\u00e9e d\u2019\u00e9ducation fondamentale, elle a grandi et \u00e9volu\u00e9 au sein de cet environnement \u00e9ducatif qui valorise \u00e0 la fois l\u2019excellence acad\u00e9mique et la formation humaine.<\/p>\n<p>Ce succ\u00e8s n\u2019est pas seulement le r\u00e9sultat d\u2019un effort individuel. Il refl\u00e8te \u00e9galement la qualit\u00e9 de l\u2019accompagnement offert par les \u00e9ducateurs \u2013 religieuses et la\u00efcs \u2013 ainsi que l\u2019attention port\u00e9e \u00e0 chaque \u00e9l\u00e8ve dans son d\u00e9veloppement int\u00e9gral. Fid\u00e8le \u00e0 sa mission \u00e9ducative, l\u2019Ecole continue de former des jeunes capables de penser, de s\u2019exprimer et de s\u2019engager de mani\u00e8re responsable dans la soci\u00e9t\u00e9.<\/p>\n<p>La reconnaissance \u00e0 Nissa Victoria repr\u00e9sente une source de fiert\u00e9 pour l\u2019ensemble du R\u00e9seau \u00e9ducatif des FMA, confirmant l\u2019importance de promouvoir des espaces o\u00f9 les jeunes peuvent d\u00e9velopper leur propre voix, leur cr\u00e9ativit\u00e9 et leur sens des relations humaines, notamment dans un contexte o\u00f9 les interactions passent de plus en plus \u00e0 travers des \u00e9crans.<\/p>\n<p>Au-del\u00e0 de la performance, ce prix transmet un message fort\u00a0: m\u00eame \u00e0 l\u2019\u00e8re num\u00e9rique, la qualit\u00e9 des relations humaines reste essentielle. Les jeunes, lorsqu\u2019ils sont accompagn\u00e9s et encourag\u00e9s, sont capables d\u2019offrir un regard profond et porteur d\u2019espoir sur le monde qui les entoure, m\u00eame dans une situation dramatique comme celle qu\u2019ils vivent \u00e0 Ha\u00efti en ce moment.<\/p>\n<p>Le r\u00e9seau des Centres de Formation Professionnelle (CFP) et les Ecole Sal\u00e9sienne des FMA \u00e0 Ha\u00efti exprime sa gratitude envers les bienfaiteurs et les r\u00e9alit\u00e9s sal\u00e9siennes pour le soutien \u00e9conomique et la solidarit\u00e9 qui continuent \u00e0 faire briller tant d\u2019\u00e9tincelles de talents cach\u00e9s dans l\u2019ombre.<\/p>\n<p>Cette r\u00e9ussite rappelle \u00e0 quel point il est fondamental de continuer \u00e0 investir dans l\u2019\u00e9ducation, en particulier pour les enfants et les jeunes qui vivent des situations difficiles. Le soutien est essentiel afin de leur offrir des opportunit\u00e9s de croissance, des espaces d\u2019expression et un avenir plus digne, pour aider ensemble de nombreux jeunes talents \u00e0 \u00e9merger et \u00e0 construire, par l\u2019\u00e9ducation, des relations humaines plus solides et une soci\u00e9t\u00e9 plus solidaire.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15265 size-full\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-2.15.20-PM.jpeg?resize=810%2C888&#038;ssl=1\" alt=\"\" width=\"810\" height=\"888\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-2.15.20-PM.jpeg?w=810&amp;ssl=1 810w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-2.15.20-PM.jpeg?resize=274%2C300&amp;ssl=1 274w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-2.15.20-PM.jpeg?resize=768%2C842&amp;ssl=1 768w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 30 avril 2026, \u00e0 Port-au-Prince, Ha\u00efti, une \u00e9tudiante de l\u2019Ecole des FMA de P\u00e9tion-Ville a remport\u00e9 le 3\u00e8me prix du concours national de composition&hellip;<\/p>\n","protected":false},"author":4,"featured_media":15263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-15262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-30-at-10.48.47-AM.jpeg?fit=750%2C1000&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcR5kd-3Ya","jetpack-related-posts":[{"id":14418,"url":"https:\/\/fmahaiti.org\/site\/2026\/02\/02\/90-ans-de-mission-salesienne-sur-la-terre-dhaiti-pour-les-salesiens-de-don-bosco-sdb\/","url_meta":{"origin":15262,"position":0},"title":"90 ans de mission Sal\u00e9sienne sur la terre d\u2019Ha\u00efti pour les Sal\u00e9siens de Don Bosco (SDB)!","author":"Sr Monette Octave","date":"2 f\u00e9vrier 2026","format":false,"excerpt":"Quelle joie de nous rassembler en Famille, le Samedi 31 Janvier 2026, \u00e0 la chapelle de St Jean Bosco \u00e0 P\u00e9tion-Ville, \u00a0pour lancer officiellement l\u2019ouverture du Jubil\u00e9 des 90 ans des Sal\u00e9siens de Don Bosco en Ha\u00efti et les 75 ans de la Chapelle de Saint Jean Bosco \u00e0 P\u00e9tion-Ville\u2026","rel":"","context":"Dans &quot;Eglise&quot;","block_context":{"text":"Eglise","link":"https:\/\/fmahaiti.org\/site\/category\/eglise\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/23450a4d-69e3-43eb-8287-29a3a11559d4-1.jpeg?fit=937%2C432&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/23450a4d-69e3-43eb-8287-29a3a11559d4-1.jpeg?fit=937%2C432&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/23450a4d-69e3-43eb-8287-29a3a11559d4-1.jpeg?fit=937%2C432&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/23450a4d-69e3-43eb-8287-29a3a11559d4-1.jpeg?fit=937%2C432&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":14573,"url":"https:\/\/fmahaiti.org\/site\/2026\/02\/03\/un-reve-enracine-dans-le-coeur-des-jeunes\/","url_meta":{"origin":15262,"position":1},"title":"Un r\u00eave enracin\u00e9 dans le c\u0153ur des jeunes!","author":"La Saline Port-au-Prince","date":"3 f\u00e9vrier 2026","format":false,"excerpt":"Saint Jean Bosco, pr\u00eatre et \u00e9ducateur passionn\u00e9, a consacr\u00e9 toute sa vie aux enfants et aux jeunes, en particulier aux plus pauvres et aux plus abandonn\u00e9s. Il \u00e9tait convaincu que chaque jeune porte en lui un tr\u00e9sor \u00e0 d\u00e9couvrir et \u00e0 faire grandir. \u00c0 travers son Syst\u00e8me Pr\u00e9ventif, fond\u00e9 sur\u2026","rel":"","context":"Dans &quot;Sal\u00e9sianit\u00e9&quot;","block_context":{"text":"Sal\u00e9sianit\u00e9","link":"https:\/\/fmahaiti.org\/site\/category\/salesianite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-8.45.28-PM-1.jpeg?fit=769%2C562&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-8.45.28-PM-1.jpeg?fit=769%2C562&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-8.45.28-PM-1.jpeg?fit=769%2C562&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-8.45.28-PM-1.jpeg?fit=769%2C562&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":14666,"url":"https:\/\/fmahaiti.org\/site\/2026\/02\/13\/carnaval-au-kindergarten-de-linstitution-saint-joseph-educateur-cest-waw\/","url_meta":{"origin":15262,"position":2},"title":"Carnaval au kindergarten de l&rsquo;Institution Saint Joseph Educateur : c\u2019est waw !","author":"Joseph Educateur Anse-a-Veaux","date":"13 f\u00e9vrier 2026","format":false,"excerpt":"Jeudi 12 f\u00e9vrier 2026. D\u00e8s 7h45, la cour de notre \u00e9cole s\u2019est m\u00e9tamorphos\u00e9e en un v\u00e9ritable th\u00e9\u00e2tre de f\u00eate et de convivialit\u00e9. La matin\u00e9e a d\u00e9but\u00e9 dans la ferveur, sous la conduite de S\u0153ur Rose Galie Jeanvier, qui a plac\u00e9 cet \u00e9v\u00e9nement sous la protection divine. Le carnaval, ce n\u2019est\u2026","rel":"","context":"Dans &quot;Activit\u00e9s&quot;","block_context":{"text":"Activit\u00e9s","link":"https:\/\/fmahaiti.org\/site\/category\/activites\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-14-at-10.37.14-AM.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-14-at-10.37.14-AM.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-14-at-10.37.14-AM.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-14-at-10.37.14-AM.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-14-at-10.37.14-AM.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7080,"url":"https:\/\/fmahaiti.org\/site\/2023\/12\/18\/marie-premiere-gardienne-de-la-creation-port-au-prince-thorland-carrefour-haiti\/","url_meta":{"origin":15262,"position":3},"title":"\u00ab\u00a0Marie, premi\u00e8re gardienne de la cr\u00e9ation\u00a0\u00bb                                                                                        Port-au-Prince \u2013 Thorland &#8211;  Carrefour, Ha\u00efti.","author":"Noviciat FMA Thorland","date":"18 d\u00e9cembre 2023","format":false,"excerpt":"\u00a0 \u00ab Marie, premi\u00e8re gardienne de la cr\u00e9ation ; \u00a0Manman pa bliye nou te pale yon paw\u00f2l. \u00bb \u00a0Les communaut\u00e9s \u00a0de Marie R\u00e9gine, du Noviciat Marie Auxiliatrice et du \u00a0pr\u00e9-Noviciat des sal\u00e9siens de Don Bosco ont r\u00e9alis\u00e9 la f\u00eate de l\u2019Immacul\u00e9e Conception avec le peuple de Dieu de Carrefour\u00a0 autour\u2026","rel":"","context":"Dans &quot;Ecologie&quot;","block_context":{"text":"Ecologie","link":"https:\/\/fmahaiti.org\/site\/category\/ecologie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2023\/12\/Imma-6.jpg?fit=468%2C309&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14502,"url":"https:\/\/fmahaiti.org\/site\/2026\/02\/04\/30eme-journee-internationale-de-la-vie-consacree-dans-larchidiocese-de-port-au-prince\/","url_meta":{"origin":15262,"position":4},"title":"30\u00e8me Journ\u00e9e Internationale de la Vie Consacr\u00e9e dans l\u2019Archidioc\u00e8se de Port-au-Prince","author":"Sr Monette Octave","date":"4 f\u00e9vrier 2026","format":false,"excerpt":"Institu\u00e9e par Saint Jean-Paul II en 1997, \u00e0 la suite de l'exhortation apostolique post-synodale Vita Consecrata, la journ\u00e9e mondiale de la Vie Consacr\u00e9e co\u00efncide avec la f\u00eate de la Pr\u00e9sentation de J\u00e9sus au Temple. Cette journ\u00e9e met en lumi\u00e8re la richesse et la diversit\u00e9 de la vie consacr\u00e9e dans l'\u00c9glise\u2026","rel":"","context":"Dans &quot;Eglise&quot;","block_context":{"text":"Eglise","link":"https:\/\/fmahaiti.org\/site\/category\/eglise\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/e72e2b5a-3930-49d1-a8cb-40ea06be1403.jpeg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/e72e2b5a-3930-49d1-a8cb-40ea06be1403.jpeg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/e72e2b5a-3930-49d1-a8cb-40ea06be1403.jpeg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/e72e2b5a-3930-49d1-a8cb-40ea06be1403.jpeg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":14786,"url":"https:\/\/fmahaiti.org\/site\/2026\/02\/14\/un-carnaval-haut-en-couleurs-a-linstitution-marie-auxiliatrice-entre-exploration-et-espoir\/","url_meta":{"origin":15262,"position":5},"title":"Un Carnaval Haut en Couleurs \u00e0 l\u2019Institution Marie Auxiliatrice : Entre Exploration et Espoir","author":"Marie Auxiliatrice Cap-Haitien","date":"14 f\u00e9vrier 2026","format":false,"excerpt":"Le\u00a0carnaval\u00a0est\u00a0une\u00a0p\u00e9riode\u00a0festive, une manifestation\u00a0culturelle\u00a0\u00a0 qui\u00a0pr\u00e9c\u00e8de\u00a0le\u00a0mercredi\u00a0des\u00a0Cendres.\u00a0Pendant\u00a0cette\u00a0p\u00e9riode,\u00a0les\u00a0habitants\u00a0se\u00a0rassemblent\u00a0pour\u00a0chanter,\u00a0danser,\u00a0faire\u00a0de\u00a0la\u00a0musique,\u00a0et\u00a0c\u00e9l\u00e9brer\u00a0avec\u00a0des\u00a0d\u00e9fil\u00e9s\u00a0de\u00a0costumes\u00a0color\u00e9s\u00a0et\u00a0des\u00a0bals.\u00a0Les\u00a0carnavals\u00a0sont\u00a0souvent\u00a0associ\u00e9s\u00a0\u00e0\u00a0des\u00a0rituels\u00a0antiques\u00a0 et\u00a0sont\u00a0des\u00a0moments\u00a0de\u00a0joie\u00a0et\u00a0de\u00a0divertissement\u00a0dans\u00a0diverses\u00a0cultures. Cette ann\u00e9e encore, l\u2019Institution Marie Auxiliatrice a vibr\u00e9, les 12 et 13 f\u00e9vrier 2026, au rythme du carnaval. Entre \u00e9vasion culturelle pour les plus petits et engagement citoyen pour les grands. La communaut\u00e9 \u00e9ducative a c\u00e9l\u00e9br\u00e9 la tradition dans une ambiance \u00e9lectrique et p\u00e9dagogique. Le\u2026","rel":"","context":"Dans &quot;Activit\u00e9s&quot;","block_context":{"text":"Activit\u00e9s","link":"https:\/\/fmahaiti.org\/site\/category\/activites\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/IMG-20260218-WA0013.jpg?fit=833%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/IMG-20260218-WA0013.jpg?fit=833%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/IMG-20260218-WA0013.jpg?fit=833%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/IMG-20260218-WA0013.jpg?fit=833%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts\/15262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/comments?post=15262"}],"version-history":[{"count":1,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts\/15262\/revisions"}],"predecessor-version":[{"id":15266,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts\/15262\/revisions\/15266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/media\/15263"}],"wp:attachment":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/media?parent=15262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/categories?post=15262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/tags?post=15262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}