{"id":14418,"date":"2026-02-02T17:19:46","date_gmt":"2026-02-02T22:19:46","guid":{"rendered":"https:\/\/fmahaiti.org\/site\/?p=14418"},"modified":"2026-02-02T17:20:05","modified_gmt":"2026-02-02T22:20:05","slug":"90-ans-de-mission-salesienne-sur-la-terre-dhaiti-pour-les-salesiens-de-don-bosco-sdb","status":"publish","type":"post","link":"https:\/\/fmahaiti.org\/site\/2026\/02\/02\/90-ans-de-mission-salesienne-sur-la-terre-dhaiti-pour-les-salesiens-de-don-bosco-sdb\/","title":{"rendered":"90 ans de mission Sal\u00e9sienne sur la terre d\u2019Ha\u00efti pour les Sal\u00e9siens de Don Bosco (SDB)!"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14420 size-full\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/23450a4d-69e3-43eb-8287-29a3a11559d4-1.jpeg?resize=843%2C389&#038;ssl=1\" alt=\"\" width=\"843\" height=\"389\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/23450a4d-69e3-43eb-8287-29a3a11559d4-1.jpeg?w=937&amp;ssl=1 937w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/23450a4d-69e3-43eb-8287-29a3a11559d4-1.jpeg?resize=300%2C138&amp;ssl=1 300w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/23450a4d-69e3-43eb-8287-29a3a11559d4-1.jpeg?resize=768%2C354&amp;ssl=1 768w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/p>\n<p>Quelle joie de nous rassembler en Famille, le Samedi 31 Janvier 2026, \u00e0 la chapelle de St Jean Bosco \u00e0<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14433 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/55241486-745d-46ea-9eb9-7e620df73eed.jpeg?resize=201%2C300&#038;ssl=1\" alt=\"\" width=\"201\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/55241486-745d-46ea-9eb9-7e620df73eed.jpeg?resize=201%2C300&amp;ssl=1 201w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/55241486-745d-46ea-9eb9-7e620df73eed.jpeg?w=462&amp;ssl=1 462w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/> P\u00e9tion-Ville, \u00a0pour lancer officiellement l\u2019ouverture du Jubil\u00e9 des 90 ans des Sal\u00e9siens de Don Bosco en Ha\u00efti et les 75 ans de la Chapelle de Saint Jean Bosco \u00e0 P\u00e9tion-Ville \u00e0 l\u2019occasion de la f\u00eate de notre Saint Fondateur!<\/p>\n<p>Nous avons remerci\u00e9 le Seigneur pour son amour fid\u00e8le qui a soutenu les Sal\u00e9siens malgr\u00e9 les temp\u00eates de la vie pour semer l\u2019esp\u00e9rance dans le c\u0153ur des jeunes depuis 90 ans, sp\u00e9cialement dans la premi\u00e8re \u0153uvre \u00e0 l\u2019\u00ab\u00a0ENAM\u00a0= Ecole Nationale des Arts et M\u00e9tiers, un centre de Formation Technique et Professionnelle \u00e0 La Saline\u00bb. C\u2019est l\u00e0 que tout a commenc\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>Le P\u00e8re Morachel Bonhomme, le Provincial des Sal\u00e9siens d\u2019Ha\u00efti, dans son hom\u00e9lie inspir\u00e9e des trois textes du jour, particuli\u00e8rement l\u2019\u00e9vangile de St Mathieu 18, 1-6, 10 a insist\u00e9 sur l\u2019acte symbolique pos\u00e9 par J\u00e9sus qui nous offre une le\u00e7on fondamentale de l&rsquo;humilit\u00e9 et de l&rsquo;attention aux plus fragiles \u00ab\u00a0les petits\u00a0\u00bb. J\u00e9sus nous appelle \u00e0 devenir comme des enfants pour entrer dans le Royaume, invitant l&rsquo;\u00c9ducateur sal\u00e9sien \u00e0 placer la simplicit\u00e9, la confiance et la vuln\u00e9rabilit\u00e9 des jeunes au centre de sa mission pr\u00e9ventive.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14424 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/d6718ef0-c92b-4073-9530-9362f8e0a678.jpeg?resize=300%2C139&#038;ssl=1\" alt=\"\" width=\"300\" height=\"139\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/d6718ef0-c92b-4073-9530-9362f8e0a678.jpeg?resize=300%2C139&amp;ssl=1 300w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/d6718ef0-c92b-4073-9530-9362f8e0a678.jpeg?resize=768%2C355&amp;ssl=1 768w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/d6718ef0-c92b-4073-9530-9362f8e0a678.jpeg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Recevoir un jeune, c&rsquo;est recevoir J\u00e9sus lui-m\u00eame. L&rsquo;accueil inconditionnel est un acte non seulement p\u00e9dagogique mais th\u00e9ologal. Le Sal\u00e9sien doit veiller avec une grande responsabilit\u00e9 \u00e0 ne pas m\u00e9priser ni \u00e9garer les jeunes.<\/p>\n<p>Cette approche de J\u00e9sus r\u00e9sonne directement avec l&rsquo;esprit de famille de Don Bosco, o\u00f9 l&rsquo;attention aimante (amorevolezza) prot\u00e8ge la fragilit\u00e9 des jeunes et les guide vers leur salut.<\/p>\n<p>Mathieu invite le Sal\u00e9sien \u00e0 placer le jeune, tel un petit enfant, au centre de sa pastorale, incarnant la \u00ab pr\u00e9sence \u00bb divine par une assistance pr\u00e9venante et humble. L&rsquo;assistance sal\u00e9sienne est une pr\u00e9sence qui s\u00e9curise, guide et prot\u00e8ge, emp\u00eachant que les jeunes ne se perdent ou ne soient bless\u00e9s dans leur parcours de croissance. L&rsquo;accueil, la tendresse et la familiarit\u00e9 (amorevolezza) sont la mani\u00e8re de cr\u00e9er cet environnement bienveillant o\u00f9 le jeune se sent aim\u00e9, ce qui est le pilier affectif de Don Bosco.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14425 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/25fffc5a-4431-43c5-a383-4d37544ae9ba.jpeg?resize=300%2C139&#038;ssl=1\" alt=\"\" width=\"300\" height=\"139\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/25fffc5a-4431-43c5-a383-4d37544ae9ba.jpeg?resize=300%2C139&amp;ssl=1 300w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/25fffc5a-4431-43c5-a383-4d37544ae9ba.jpeg?resize=768%2C355&amp;ssl=1 768w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/25fffc5a-4431-43c5-a383-4d37544ae9ba.jpeg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14430 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/99ace8f1-7155-4d04-a7f2-2bd8db21d06d.jpeg?resize=300%2C228&#038;ssl=1\" alt=\"\" width=\"300\" height=\"228\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/99ace8f1-7155-4d04-a7f2-2bd8db21d06d.jpeg?resize=300%2C228&amp;ssl=1 300w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/99ace8f1-7155-4d04-a7f2-2bd8db21d06d.jpeg?w=494&amp;ssl=1 494w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Le Sal\u00e9sien ou la Sal\u00e9sienne s&rsquo;engage \u00e0 fournir des outils n\u00e9cessaires aux jeunes leur permettant d\u2019acqu\u00e9rir un m\u00e9tier pour devenir autonome et d&rsquo;\u00eatre des producteurs de richesses pour l\u2019\u00e9panouissement de la soci\u00e9t\u00e9 ha\u00eftienne. Cela inclut la formation professionnelle, pr\u00e9parant le jeune \u00e0 la vie active pour qu&rsquo;il ne soit pas une \u00ab occasion de chute \u00bb sociale. Nous sommes donc appel\u00e9s \u00e0 \u00eatre ce compagnon qui, par notre pr\u00e9sence constante, pr\u00e9vient les dangers et offre un m\u00e9tier, assurant la croissance spirituelle et mat\u00e9rielle des jeunes les plus d\u00e9munis.<\/p>\n<p>Ce passage \u00e9vang\u00e9lique renforce l&rsquo;approche sal\u00e9sienne o\u00f9 l&rsquo;affection (amorevolezza) est le pilier central permettant \u00e0 la raison et \u00e0 la religion de transformer la vie du jeune, dans la lign\u00e9e de Don Bosco qui voyait le Christ en chaque enfant. Le sal\u00e9sien doit \u00e9duquer avec une foi profonde, consid\u00e9rant chaque jeune comme un enfant de Dieu \u00e0 respecter.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14432 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/16f51c79-4a4d-43f0-b1dd-af0a7fdf098f.jpeg?resize=300%2C139&#038;ssl=1\" alt=\"\" width=\"300\" height=\"139\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/16f51c79-4a4d-43f0-b1dd-af0a7fdf098f.jpeg?resize=300%2C139&amp;ssl=1 300w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/16f51c79-4a4d-43f0-b1dd-af0a7fdf098f.jpeg?resize=768%2C355&amp;ssl=1 768w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/16f51c79-4a4d-43f0-b1dd-af0a7fdf098f.jpeg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14426 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/bb2a1416-982b-45e2-acfc-3403a4bf6a67.jpeg?resize=139%2C300&#038;ssl=1\" alt=\"\" width=\"139\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/bb2a1416-982b-45e2-acfc-3403a4bf6a67.jpeg?resize=139%2C300&amp;ssl=1 139w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/bb2a1416-982b-45e2-acfc-3403a4bf6a67.jpeg?w=462&amp;ssl=1 462w\" sizes=\"auto, (max-width: 139px) 100vw, 139px\" \/>La spiritualit\u00e9 sal\u00e9sienne de Saint Jean Bosco est centr\u00e9e sur une saintet\u00e9 joyeuse, accessible \u00e0 tous, unissant pi\u00e9t\u00e9 et vie quotidienne. Elle repose sur la joie de vivre comme moteur spirituel, l&rsquo;\u00e9tude et le travail comme formation de l&rsquo;esprit, la musique et le chant comme expression de la foi, et une pi\u00e9t\u00e9 centr\u00e9e sur l&rsquo;Eucharistie et la Vierge Marie, le tout dans une ambiance familiale. Ces \u00e9l\u00e9ments sont int\u00e9gr\u00e9s dans le syst\u00e8me pr\u00e9ventif de Don Bosco, qui vise \u00e0 former \u00ab\u00a0d&rsquo;honn\u00eates citoyens et de bons chr\u00e9tiens\u00a0\u00bb \u00e0 travers une \u00e9ducation bienveillante au rel\u00e8vement de notre ch\u00e8re Ha\u00efti.<\/p>\n<p>Le contexte du XIXe si\u00e8cle \u00e0 Turin, en Italie, o\u00f9 vivait Don Bosco, pr\u00e9sentait des similitudes frappantes avec la r\u00e9alit\u00e9 ha\u00eftienne: une mis\u00e8re extr\u00eame, des jeunes abandonn\u00e9s, affam\u00e9s, orphelins et sans \u00e9ducation. Face \u00e0 des jeunes criminels ou en voie de le devenir, Don Bosco a cr\u00e9\u00e9 des oratoires et des \u00e9coles pour leur offrir refuge et \u00e9ducation, une mission centrale des Sal\u00e9siens et des Sal\u00e9siennes de Don Bosco en Ha\u00efti aujourd&rsquo;hui.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14431 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/d43bab0b-513e-4f25-86d2-0c2e7540272e.jpeg?resize=290%2C300&#038;ssl=1\" alt=\"\" width=\"290\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/d43bab0b-513e-4f25-86d2-0c2e7540272e.jpeg?resize=290%2C300&amp;ssl=1 290w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/d43bab0b-513e-4f25-86d2-0c2e7540272e.jpeg?w=462&amp;ssl=1 462w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><\/p>\n<p>Le C\u00e9l\u00e9brant a insist\u00e9 sur la t\u00e9nacit\u00e9, synonyme de volont\u00e9 et de pers\u00e9v\u00e9rance, comme mot qui r\u00e9sume le mieux l&rsquo;attitude de Don Bosco. Cette t\u00e9nacit\u00e9 est caract\u00e9ris\u00e9e par une passion et une pers\u00e9v\u00e9rance in\u00e9branlables dans la r\u00e9alisation de ses objectifs \u00e9ducatifs \u00e0 long terme, malgr\u00e9 les obstacles. V\u00e9ritable pilier, cette qualit\u00e9 lui a permis de ne jamais abandonner face aux d\u00e9fis, persistant dans ses efforts jusqu&rsquo;\u00e0 la r\u00e9ussite de sa mission.<\/p>\n<p>Les Sal\u00e9siennes pr\u00e9sentes en Ha\u00efti depuis 1935 et les Sal\u00e9siens en Ha\u00efti depuis 1936, poursuivent ce m\u00eame h\u00e9ritage en travaillant avec les enfants des rues, les centres de jeunes et les \u00e9coles classiques et professionnelles pour lutter contre la pauvret\u00e9.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14421 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/f103ba51-189e-423b-864c-196ad5f537d4.jpeg?resize=155%2C300&#038;ssl=1\" alt=\"\" width=\"155\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/f103ba51-189e-423b-864c-196ad5f537d4.jpeg?resize=155%2C300&amp;ssl=1 155w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/f103ba51-189e-423b-864c-196ad5f537d4.jpeg?w=462&amp;ssl=1 462w\" sizes=\"auto, (max-width: 155px) 100vw, 155px\" \/>En partageant le quotidien, les repas et les activit\u00e9s, les la\u00efcs et les jeunes s&rsquo;impr\u00e8gnent de notre mission \u00e9ducative. C&rsquo;est une communion de vie qui favorise l&rsquo;accompagnement des jeunes. C\u2019est ce qui nous diff\u00e8re des autres.<\/p>\n<p>\u00ab\u00a0Nou pa ka chanje peyi a si nou pa chanje lavi j\u00e8n yo\u00a0\u00bb<\/p>\n<p>P\u00e8re Morachel a invit\u00e9 les la\u00efcs \u00e0 devenir des Sal\u00e9siens et des Sal\u00e9siennes par osmose. Il a lanc\u00e9 un vibrant appel aux SDB,\u00a0 aux FMA et aux autres membres de la Famille Sal\u00e9sienne\u00a0: \u00ab\u00a0Que l\u2019amour soit votre unique devise. Seul l\u2019amour aura le dernier mot. Soyons des hommes et des femmes de pri\u00e8re\u00a0!<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14428 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/31eeb34b-389f-4119-8da1-a55342f52e30.jpeg?resize=185%2C300&#038;ssl=1\" alt=\"\" width=\"185\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/31eeb34b-389f-4119-8da1-a55342f52e30.jpeg?resize=185%2C300&amp;ssl=1 185w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/31eeb34b-389f-4119-8da1-a55342f52e30.jpeg?w=462&amp;ssl=1 462w\" sizes=\"auto, (max-width: 185px) 100vw, 185px\" \/><\/p>\n<p>Une d\u00e9l\u00e9gation officielle de la Mairie de P\u00e9tion-Ville conduite par le Magistrat principal Kesner NORMIL a particip\u00e9 \u00e0 cet \u00e9v\u00e8nement.<\/p>\n<p>Suite \u00e0 la C\u00e9l\u00e9bration Eucharistique, nous avons eu l\u2019agape en plein air, un moment privil\u00e9gi\u00e9 de communion spirituelle et humaine. Dans la tradition Sal\u00e9sienne, la joie et la convivialit\u00e9 sont souvent agr\u00e9ment\u00e9s par une partie culturelle pour renforcer les liens de la communaut\u00e9. Une partie de la f\u00eate \u00e9tait spontan\u00e9e. Chaque groupe qui constituait l\u2019Assembl\u00e9e devait pr\u00e9senter un num\u00e9ro. C\u2019\u00e9tait une ambiance cr\u00e9ative et participative.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14422 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/ce1282cc-0112-4dce-893f-325d0a8210b6.jpeg?resize=300%2C139&#038;ssl=1\" alt=\"\" width=\"300\" height=\"139\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/ce1282cc-0112-4dce-893f-325d0a8210b6.jpeg?resize=300%2C139&amp;ssl=1 300w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/ce1282cc-0112-4dce-893f-325d0a8210b6.jpeg?resize=768%2C355&amp;ssl=1 768w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/ce1282cc-0112-4dce-893f-325d0a8210b6.jpeg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>L&rsquo;initiative spontan\u00e9e de chaque groupe de l&rsquo;Assembl\u00e9e \u00e0 pr\u00e9senter un \u00ab\u00a0num\u00e9ro\u00a0\u00bb symbolise ce que Don Bosco faisait en son temps. Chaque groupe participait activement \u00e0 la performance de fa\u00e7on improvis\u00e9e.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-14418-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Video-2026-01-31-at-7.52.09-PM.mp4?_=1\" \/><a href=\"https:\/\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Video-2026-01-31-at-7.52.09-PM.mp4\">https:\/\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/WhatsApp-Video-2026-01-31-at-7.52.09-PM.mp4<\/a><\/video><\/div>\n<p>La police nationale est souvent pr\u00e9sente pour garantir la s\u00e9curit\u00e9 des personnes, cette fois-ci,<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14429 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/ea9f62a6-2f2f-4f1b-84b7-c9adbbad7ced.jpeg?resize=139%2C300&#038;ssl=1\" alt=\"\" width=\"139\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/ea9f62a6-2f2f-4f1b-84b7-c9adbbad7ced.jpeg?resize=139%2C300&amp;ssl=1 139w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/ea9f62a6-2f2f-4f1b-84b7-c9adbbad7ced.jpeg?w=462&amp;ssl=1 462w\" sizes=\"auto, (max-width: 139px) 100vw, 139px\" \/> accompagnant\u00a0la mairie, ce groupe de policiers a pr\u00e9sent\u00e9 plusieurs num\u00e9ros artistiques qui ont charm\u00e9 le public. Un moment qui met en lumi\u00e8re une facette plus humaine et accessible de la police nationale.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14427 size-medium\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/64b14165-29f2-4e78-9a71-e370b5097b3b-300x139.jpeg?resize=300%2C139&#038;ssl=1\" alt=\"\" width=\"300\" height=\"139\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/64b14165-29f2-4e78-9a71-e370b5097b3b.jpeg?resize=300%2C139&amp;ssl=1 300w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/64b14165-29f2-4e78-9a71-e370b5097b3b.jpeg?resize=768%2C355&amp;ssl=1 768w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/64b14165-29f2-4e78-9a71-e370b5097b3b.jpeg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Cet \u00e9v\u00e8nement a \u00e9t\u00e9 pour la Famille Sal\u00e9sienne une activit\u00e9 r\u00e9ussie malgr\u00e9 la situation s\u00e9curitaire critique \u00e0 Port-au-Prince. Cet \u00e9v\u00e9nement a constitu\u00e9 un temps fort de r\u00e9silience et d&rsquo;unit\u00e9 pour la Famille Sal\u00e9sienne qui t\u00e9moigne de leur engagement continu\u00a0pour offrir de l&rsquo;espoir \u00e0 la jeunesse ha\u00eftienne, souvent victime de la crise.<\/p>\n<p style=\"text-align: center;\"><strong>1936-2026 = Bon 90 ans aux Sal\u00e9siens de Don Bosco en Ha\u00efti\u00a0!<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14419 size-full\" src=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/09b8b9a0-5a7d-4ad8-8d9f-de5428a334f4.jpeg?resize=843%2C384&#038;ssl=1\" alt=\"\" width=\"843\" height=\"384\" srcset=\"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/09b8b9a0-5a7d-4ad8-8d9f-de5428a334f4.jpeg?w=910&amp;ssl=1 910w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/09b8b9a0-5a7d-4ad8-8d9f-de5428a334f4.jpeg?resize=300%2C136&amp;ssl=1 300w, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/09b8b9a0-5a7d-4ad8-8d9f-de5428a334f4.jpeg?resize=768%2C349&amp;ssl=1 768w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelle joie de nous rassembler en Famille, le Samedi 31 Janvier 2026, \u00e0 la chapelle de St Jean Bosco \u00e0 P\u00e9tion-Ville, \u00a0pour lancer officiellement l\u2019ouverture&hellip;<\/p>\n","protected":false},"author":4,"featured_media":14420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,18,15],"tags":[],"class_list":["post-14418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eglise","category-famille-salesienne","category-salesianite"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/23450a4d-69e3-43eb-8287-29a3a11559d4-1.jpeg?fit=937%2C432&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcR5kd-3Ky","jetpack-related-posts":[{"id":3733,"url":"https:\/\/fmahaiti.org\/site\/2022\/08\/27\/une-salesienne-en-plus-au-paradis\/","url_meta":{"origin":14418,"position":0},"title":"Une Sal\u00e9sienne en plus au paradis","author":"Sr. Marie Pierrette Louijuste","date":"27 ao\u00fbt 2022","format":false,"excerpt":"\u2021 La famille sal\u00e9sienne en Haiti est en deuil! Suivre en direct les fun\u00e9railles https:\/\/youtube.com\/channel\/UCgMBVBmwMjyxtM3yttRMNvA Annonce Mortuaire Les Filles de Marie Auxiliatrice ou S\u0153urs Sal\u00e9siennes de Don Bosco, \u00a0les familles Jean Charles, Victor, Bowman, Joseph, Jean Fran\u00e7ois et l\u2019Entreprise Celcis annoncent\u00a0le d\u00e9part\u00a0pour la Maison du P\u00e8re,\u00a0de leur regrett\u00e9e\u00a0S\u0153ur\u00a0Marie Lourdes Bernadette\u2026","rel":"","context":"Dans &quot;Annonces&quot;","block_context":{"text":"Annonces","link":"https:\/\/fmahaiti.org\/site\/category\/annonces\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/08\/Sr-Bernad-4.jpg?fit=768%2C382&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/08\/Sr-Bernad-4.jpg?fit=768%2C382&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/08\/Sr-Bernad-4.jpg?fit=768%2C382&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/08\/Sr-Bernad-4.jpg?fit=768%2C382&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7661,"url":"https:\/\/fmahaiti.org\/site\/2024\/02\/05\/sans-foule-celebrons-notre-fondateur-avec-grandeur-et-ferveur\/","url_meta":{"origin":14418,"position":1},"title":"Sans foule,  C\u00e9l\u00e9brons notre Fondateur  avec grandeur et ferveur.","author":"Dominique Mazzarello Petion-Ville","date":"5 f\u00e9vrier 2024","format":false,"excerpt":"Alors que le coll\u00e8ge Marie Dominique Mazzarello, se pr\u00e9pare \u00e0 c\u00e9l\u00e9brer la f\u00eate de notre P\u00e8re Saint Jean Bosco, une gr\u00e8ve intervient pour les 29-30-et 31 janvier 2024 sous l\u2019initiative de la Brigade syndicale anti-corruption(BSAC).Une situation qui nous contraint de c\u00e9l\u00e9brer le p\u00e8re et maitre de la jeunesse, sans les\u2026","rel":"","context":"Dans &quot;Eglise&quot;","block_context":{"text":"Eglise","link":"https:\/\/fmahaiti.org\/site\/category\/eglise\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-04-at-11.20.08.jpeg?fit=449%2C869&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3016,"url":"https:\/\/fmahaiti.org\/site\/2022\/01\/31\/bonne-fete-de-saint-jean-bosco\/","url_meta":{"origin":14418,"position":2},"title":"Bonne F\u00eate de Saint Jean Bosco","author":"Sr Martha Seide","date":"31 janvier 2022","format":false,"excerpt":"Quelques traits de sa vie: Jean Bosco est n\u00e9 le 16 ao\u00fbt 1815, \u00e0 Castelnuovo d\u2019Asti, pr\u00e8s de Turin (Nord de l\u2019Italie).\u00a0Il est le troisi\u00e8me gar\u00e7on d\u2019une famille de modestes cultivateurs. \u00c0 9 ans, un \u201cr\u00eave\u201d oriente sa vocation d\u2019\u00e9ducateur. \u00c0 16 ans, il entre au coll\u00e8ge et doit travailler\u2026","rel":"","context":"Dans &quot;Famille Sal\u00e9sienne&quot;","block_context":{"text":"Famille Sal\u00e9sienne","link":"https:\/\/fmahaiti.org\/site\/category\/famille-salesienne\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/01\/saint-jean-bosco.jpg?fit=780%2C437&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/01\/saint-jean-bosco.jpg?fit=780%2C437&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/01\/saint-jean-bosco.jpg?fit=780%2C437&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/01\/saint-jean-bosco.jpg?fit=780%2C437&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3035,"url":"https:\/\/fmahaiti.org\/site\/2022\/01\/31\/ceremonie-dinstallation-du-nouveau-provincial-des-salesiens-dhaiti\/","url_meta":{"origin":14418,"position":3},"title":"C\u00e9r\u00e9monie d\u2019installation du Nouveau Provincial des Sal\u00e9siens d\u2019Ha\u00efti","author":"Sr Monette Octave","date":"31 janvier 2022","format":false,"excerpt":"C\u2019est au cours de la messe Dominicale du 30 Janvier 2022 \u00e0 Saint Jean Bosco \u00e0 P\u00e9tion-ville\u00a0 aux environs de 11 hres AM\u00a0 qu\u2019on a install\u00e9 le R\u00e9v\u00e9rend P. Morachel Bonhomme SDB, comme nouveau Sup\u00e9rieur de la Vice Province Don Philippe Rinaldi des Sal\u00e9siens de Don Bosco en Ha\u00efti. La\u2026","rel":"","context":"Dans &quot;Famille Sal\u00e9sienne&quot;","block_context":{"text":"Famille Sal\u00e9sienne","link":"https:\/\/fmahaiti.org\/site\/category\/famille-salesienne\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/01\/20220130_121637-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/01\/20220130_121637-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/01\/20220130_121637-scaled.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/01\/20220130_121637-scaled.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2022\/01\/20220130_121637-scaled.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14389,"url":"https:\/\/fmahaiti.org\/site\/2026\/02\/02\/celebration-de-la-saint-jean-bosco-a-linstitution-marie-regine\/","url_meta":{"origin":14418,"position":4},"title":"C\u00e9l\u00e9bration de la Saint-Jean Bosco \u00e0 l&rsquo;Institution Marie R\u00e9gine","author":"Marie Regine Thorland","date":"2 f\u00e9vrier 2026","format":false,"excerpt":"La Communaut\u00e9 \u00e9ducative de l\u2019Institution Marie R\u00e9gine des S\u0153urs Sal\u00e9siennes de Carrefour a c\u00e9l\u00e9br\u00e9 dans la foi et la ferveur, les vendredi 30 et samedi 31 janvier 2026, la solennit\u00e9 de la f\u00eate de Saint Jean Bosco, p\u00e8re et ma\u00eetre de la jeunesse. Fid\u00e8les aux souhaits du saint patron, les\u2026","rel":"","context":"Dans &quot;Famille Sal\u00e9sienne&quot;","block_context":{"text":"Famille Sal\u00e9sienne","link":"https:\/\/fmahaiti.org\/site\/category\/famille-salesienne\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/IMG-20260201-WA0188.jpg?fit=1200%2C679&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/IMG-20260201-WA0188.jpg?fit=1200%2C679&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/IMG-20260201-WA0188.jpg?fit=1200%2C679&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/IMG-20260201-WA0188.jpg?fit=1200%2C679&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2026\/02\/IMG-20260201-WA0188.jpg?fit=1200%2C679&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1808,"url":"https:\/\/fmahaiti.org\/site\/2021\/06\/08\/deuil-dans-la-famille-et-dans-leglise\/","url_meta":{"origin":14418,"position":5},"title":"Deuil dans la Famille et dans l&rsquo;Eglise &#8211; livre d&rsquo;or","author":"Sr Martha Seide","date":"8 juin 2021","format":false,"excerpt":"L\u2019\u00e9v\u00eaque auxiliaire de Port-au-Prince, Mgr Ducange Sylvain est d\u00e9c\u00e9d\u00e9 ce matin (08 juin 2021) \u00e0 l\u2019h\u00f4pital universitaire de Mirebalais suite \u00e0 des complications li\u00e9es au coronavirus. Il avait 58 ans. Mgr Sylvain Ducange avait \u00e9t\u00e9 transf\u00e9r\u00e9 \u00e0 l\u2019HUM le lundi 31 mai dernier \u00e0 cause de graves complications respiratoires. Il\u2026","rel":"","context":"Dans &quot;Annonces&quot;","block_context":{"text":"Annonces","link":"https:\/\/fmahaiti.org\/site\/category\/annonces\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/fmahaiti.org\/site\/wp-content\/uploads\/2021\/06\/Ducange.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts\/14418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/comments?post=14418"}],"version-history":[{"count":2,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts\/14418\/revisions"}],"predecessor-version":[{"id":14436,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/posts\/14418\/revisions\/14436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/media\/14420"}],"wp:attachment":[{"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/media?parent=14418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/categories?post=14418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmahaiti.org\/site\/wp-json\/wp\/v2\/tags?post=14418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}